{"id":24204,"date":"2023-10-25T17:49:57","date_gmt":"2023-10-25T15:49:57","guid":{"rendered":"https:\/\/orchidee.de\/?post_type=mec-events&#038;p=24204"},"modified":"2023-10-25T17:49:57","modified_gmt":"2023-10-25T15:49:57","slug":"gruenes-kuba","status":"publish","type":"mec-events","link":"https:\/\/staging.orchidee.de\/en\/events\/gruenes-kuba\/","title":{"rendered":"Gr\u00fcnes Kuba"},"content":{"rendered":"<p>Wolfgang Hoffmann<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wolfgang Hoffmann<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","tags":[],"mec_category":[103],"class_list":["post-24204","mec-events","type-mec-events","status-publish","hentry","mec_category-lausitzerorchideenbund"],"_links":{"self":[{"href":"https:\/\/staging.orchidee.de\/en\/wp-json\/wp\/v2\/mec-events\/24204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.orchidee.de\/en\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/staging.orchidee.de\/en\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/staging.orchidee.de\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.orchidee.de\/en\/wp-json\/wp\/v2\/comments?post=24204"}],"wp:attachment":[{"href":"https:\/\/staging.orchidee.de\/en\/wp-json\/wp\/v2\/media?parent=24204"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.orchidee.de\/en\/wp-json\/wp\/v2\/tags?post=24204"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/staging.orchidee.de\/en\/wp-json\/wp\/v2\/mec_category?post=24204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}